{"id":2677,"date":"2017-04-04T13:35:21","date_gmt":"2017-04-04T11:35:21","guid":{"rendered":"http:\/\/spoliation.org\/?p=2677"},"modified":"2017-04-04T13:35:21","modified_gmt":"2017-04-04T11:35:21","slug":"mode-de-calcul-de-cour-dappel-dantananarivo-dommages-interets-dus-a-ranarison-tsilavo","status":"publish","type":"post","link":"https:\/\/www.madagasikara.net\/index.php\/2017\/04\/04\/mode-de-calcul-de-cour-dappel-dantananarivo-dommages-interets-dus-a-ranarison-tsilavo\/","title":{"rendered":"Mode de calcul des dommages et int\u00e9r\u00eats d\u00fbs \u00e0 RANARISON Tsilavo par la Cour d&rsquo;appel d&rsquo;Antananarivo"},"content":{"rendered":"<p>Les textes de loi malgaches (article 6 du code de proc\u00e9dure p\u00e9nale et article 181 de la loi 2003-036 r\u00e9gissant les soci\u00e9t\u00e9s commerciales) sont clairs :<\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #000080;\">c&rsquo;est la soci\u00e9t\u00e9 CONNECTIC qui est la victime du soit-disant abus des biens sociaux et non RANARISON Tsilavo, simple associ\u00e9.<\/span><\/h1>\n<p>&nbsp;<\/p>\n<p>Mais on se pose quand m\u00eame la question, comment nos juges du fond ont calcul\u00e9 les int\u00e9r\u00eats civils attribu\u00e9s \u00e0 RANARISON Tsilavo, car on ne retrouve aucune indication dans le jugement du 15 d\u00e9cembre 2015 et dans l&rsquo;arr\u00eat du 13 mai 2016<\/p>\n<p>Dans l&rsquo;affaire opposant RANARISON Tsilavo, g\u00e9rant fondateur de NEXTHOPE depuis novembre 2012, directeur ex\u00e9cutif de CONNECTIC jusqu&rsquo;en septembre 2012, la Cour d&rsquo;appel d&rsquo;Antananarivo par son arr\u00eat du 13 mai 2016 a attribu\u00e9 des dommages et int\u00e9r\u00eats s\u2019\u00e9levant \u00e0 1 500 000 000 Ariary (Un\u00a0milliard 500 millions) \u00e0 RANARISON Tsilavo.<br \/>\nRANARISON Tsilavo d\u00e9tient 20 % de la soci\u00e9t\u00e9 CONNECTIC soit disant victime d&rsquo;abus de biens sociaux de la part de Solo qui a envoy\u00e9 72 ordres virements internationaux, d&rsquo;un montant au total de 3 663 933 565,79 Ariary, tous sign\u00e9s par RANARISON Tsilavo \u00e0 la soci\u00e9t\u00e9 fran\u00e7aise EMERGENT.<\/p>\n<p>Quel est le mode de calcul des dommages et int\u00e9r\u00eats effectu\u00e9s par la Cour d&rsquo;appel d&rsquo;Antananarivo pour arriver \u00e0 1 500 000 000 Ariary (1 milliard 500 millions) pour un associ\u00e9, RANARISON Tsilavo, qui ne d\u00e9tient que 20 % des parts sociales dans la soci\u00e9t\u00e9 CONNECTIC ?<\/p>\n<h2>Le d\u00e9dommagement du pr\u00e9judice mat\u00e9riel<\/h2>\n<p>Le montant total des virements internationaux suspects s&rsquo;\u00e9l\u00e8vent \u00e0 3 663 933 565,79 Ariary, le montant du pr\u00e9judice mat\u00e9riel de RANARISON Tsilavo est calcul\u00e9 au prorata des parts d\u00e9tenues qu&rsquo;il d\u00e9tient dans la soci\u00e9t\u00e9 CONNECTIC, 20 %, et ne peut pas donc exc\u00e9der,\u00a0 732.786.713 Ariary (3 663 933 565,79 Ariary x 20 %).<\/p>\n<h2>Le d\u00e9dommagement du pr\u00e9judice moral<\/h2>\n<p>Un pr\u00e9judice moral d&rsquo;apr\u00e8s le livre d&rsquo;Eva Joly et de Caroline Joly-Baumgartner, L&rsquo;abus des biens sociaux \u00e0 l&rsquo;\u00e9preuve de la pratique peut \u00eatre indemnis\u00e9 symboliquement \u00e0 1 Ariary.<\/p>\n<h2>Comment a \u00e9t\u00e9 donc calcul\u00e9 les dommages et int\u00e9r\u00eats de 1 milliard 500 millions d&rsquo;Ariary attribu\u00e9s \u00e0 RANARISON Tsilavo par la Cour d&rsquo;appel d&rsquo;Antananarivo ?<\/h2>\n<p>Chacun sa conscience, et chacun peut tirer sa conclusion dans cette attribution de dommages et int\u00e9r\u00eats d&rsquo;autant plus que l&rsquo;infraction d&rsquo;abus de biens sociaux n&rsquo;est m\u00eame pas constitu\u00e9.<\/p>\n<h2>Quels dommages et int\u00e9r\u00eats peuvent r\u00e9clamer les victimes ? d&rsquo;apr\u00e8s Eva Joly et Caroline Joly-Baumgartner<\/h2>\n<p>Les dommages et int\u00e9r\u00eats pouvant \u00eatre rr\u00e9clam\u00e9s d\u00e9pendent de la qualit\u00e9 de la victime. Nous envisagerons successivement le cas du pr\u00e9judice subi par la soci\u00e9t\u00e9 elle-m\u00eame et celui des associ\u00e9s ou actionnaires, bien que la jurisprudence r\u00e9cente semble d\u00e9nier \u00e0 ces derniers le droit de r\u00e9paration devant la juridiction p\u00e9nale.<\/p>\n<p>Dans tous les cas, l&rsquo;\u00e9valuation du pr\u00e9judice subi par la ou les victimes d\u00e9pend de l&rsquo;appr\u00e9ciation souveraine des juges du fond.<\/p>\n<h3>1 &#8211; Dommage et int\u00e9r\u00eats pouvant \u00eatre r\u00e9clam\u00e9s par la soci\u00e9t\u00e9 victime<\/h3>\n<h4>&#8211; Pr\u00e9judice mat\u00e9riel<\/h4>\n<p>L&rsquo;action de la soci\u00e9t\u00e9 vise essentiellement \u00e0 reconstituer le patrimoine social, en r\u00e9clamant l&rsquo;\u00e9quivalant du montant de l&rsquo;abus des biens poursuivi. Le dirigeant d\u00e9clar\u00e9 coupable peut \u00eatre condamn\u00e9 non seulement \u00e0 rembourser les sommes d\u00e9tourn\u00e9es, mais \u00e9galement \u00e0 des dommages et int\u00e9r\u00eats suppl\u00e9mentaires.<\/p>\n<p>Il a \u00e9t\u00e9 admis par la jurisprudence, par exemple, que les dommages et int\u00e9r\u00eats allou\u00e9s \u00e0 une partie civile, \u00e0 la suite de l&rsquo;\u00e9mission d&rsquo;une fausse facture dans le cadre d&rsquo;un abus de biens sociaux, pourraient comprendre le montant de la TVA et les p\u00e9nalit\u00e9s fiscales li\u00e9es au retard de paiement de cette taxe.<\/p>\n<h4>&#8211; Prejudice moral<\/h4>\n<p>la soci\u00e9t\u00e9 peut \u00e9galement demander r\u00e9paration du pr\u00e9judice moral r\u00e9sultant de l&rsquo;atteinte port\u00e9e \u00e0 son cr\u00e9dit ou sa r\u00e9putation.<\/p>\n<p>L&rsquo;atteinte \u00e0 l&rsquo;image d&rsquo;une soci\u00e9t\u00e9 cot\u00e9e peut \u00eatre tr\u00e8s grave et pourrait se traduire par l&rsquo;allocation \u00e0 son profit de dommages et int\u00e9r\u00eats sans communes mesures avec les montants d\u00e9tourn\u00e9s<\/p>\n<h3>2 &#8211; Dommages et int\u00e9r\u00eats qui avaient \u00e9t\u00e9 allou\u00e9s aux associ\u00e9s ou actionnaires victimes avant le revirement de jurisprudence du 13 d\u00e9cembre 2000<\/h3>\n<p>L&rsquo;action des associ\u00e9s ou actionnaires en tant que victimes visait \u00e0 obtenir r\u00e9paration de leur pr\u00e9judice personnel alors reconnu comme distinct de celui subi par la soci\u00e9t\u00e9.<\/p>\n<h2>Conclusion : la Cour d&rsquo;appel d&rsquo;Antananarivo a fix\u00e9 les dommages et int\u00e9r\u00eats par rapport \u00e0 la capacit\u00e9 contributive de Solo<\/h2>\n<p>Il n&rsquo;y a aucune base juridique et logique pour arriver \u00e0 la somme de 1 milliard 500 millions d&rsquo;Ariary de dommages et int\u00e9r\u00eats attribu\u00e9s \u00e0 RANARISON Tsilavo en tant que partie civile.<\/p>\n<p>Les dommages et int\u00e9r\u00eats ne sont pas m\u00eame int\u00e9gr\u00e9s dans la caisse sociale de la soci\u00e9t\u00e9 mais constituent un butin net pour le plaignant. On a tout vu dans cette histoire !D&rsquo;autant plus que toutes les preuves montrent que Solo n&rsquo;a pas fait d&rsquo;abus de biens sociaux.<\/p>\n<blockquote><p>Pour aller plus loin :\u00a0<strong><a href=\"https:\/\/www.courdecassation.fr\/publications_26\/rapport_annuel_36\/rapport_2007_2640\/etude_sante_2646\/dommages_survenus_2650\/reparation_dommages_2652\/modalites_reparation_dommages_11385.html\" target=\"_blank\" rel=\"noopener noreferrer\"><em>La r\u00e9paration<\/em> doit \u00eatre, en principe, <em>int\u00e9grale <\/em>et n\u2019engendrer pour la victime ni perte ni profit.<\/a><\/strong><\/p>\n<p>ce principe ayant plusieurs cons\u00e9quences\u00a0:<br \/>\n&#8211; <strong>une r\u00e9paration forfaitaire n\u2019est pas <em>a priori <\/em>envisageable\u00a0; l\u2019ensemble du pr\u00e9judice effectivement subi par la victime devant \u00eatre pris en consid\u00e9ration<\/strong>. La Cour de cassation a pr\u00e9cis\u00e9 dans le cas de victimes en \u00e9tat v\u00e9g\u00e9tatif qu\u2019un tel \u00e9tat n\u2019excluant aucun chef d\u2019indemnisation, leur pr\u00e9judice devait \u00eatre r\u00e9par\u00e9 dans tous ses \u00e9l\u00e9ments <strong>(2<sup>e<\/sup> Civ., 28 juin 1995, Bull. 1995, II, n\u00b0\u00a0224, p. 129, pourvoi n\u00b0\u00a093-18.465\u00a0; Crim., 5 janvier 1994, Bull. crim., 1994, n\u00b0\u00a05, p. 8, pourvoi n\u00b0\u00a093-83.050)<\/strong>\u00a0;<br \/>\n&#8211; <strong>la r\u00e9paration ne peut exc\u00e9der le montant du pr\u00e9judice subi.<\/strong> La Cour de cassation en a d\u00e9duit que violait l\u2019article 1147 du code civil, une cour d\u2019appel qui avait retenu qu\u2019une victime avait perdu une chance d\u2019\u00e9viter le dommage, \u00e0 la suite de la m\u00e9connaissance par le praticien de son obligation d\u2019information, alors qu\u2019elle venait d\u2019en r\u00e9parer int\u00e9gralement les cons\u00e9quences <strong>(1<sup>re<\/sup> Civ., 22 novembre 2007, Bull. 2007, I, pourvoi n\u00b0\u00a006-14.174)\u00a0<\/strong>\u00a0;<\/p><\/blockquote>\n<h2>L&rsquo;extrait du livre d&rsquo;Eva Joly sur l&rsquo;abus des biens sociaux<\/h2>\n<p><a href=\"http:\/\/spoliation.org\/wp-content\/uploads\/2017\/04\/NEXTHOPE-RANARISON-Tsilavo-quels-dommages-et-int\u00e9r\u00eats-peuvent-r\u00e9clamer-les-victimes_Page1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2678\" src=\"http:\/\/spoliation.org\/wp-content\/uploads\/2017\/04\/NEXTHOPE-RANARISON-Tsilavo-quels-dommages-et-int\u00e9r\u00eats-peuvent-r\u00e9clamer-les-victimes_Page1.jpg\" alt=\"\" width=\"521\" height=\"913\" \/><\/a> <a href=\"http:\/\/spoliation.org\/wp-content\/uploads\/2017\/04\/NEXTHOPE-RANARISON-Tsilavo-quels-dommages-et-int\u00e9r\u00eats-peuvent-r\u00e9clamer-les-victimes_Page2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2679\" src=\"http:\/\/spoliation.org\/wp-content\/uploads\/2017\/04\/NEXTHOPE-RANARISON-Tsilavo-quels-dommages-et-int\u00e9r\u00eats-peuvent-r\u00e9clamer-les-victimes_Page2.jpg\" alt=\"\" width=\"521\" height=\"913\" \/><\/a> <a href=\"http:\/\/spoliation.org\/wp-content\/uploads\/2017\/04\/NEXTHOPE-RANARISON-Tsilavo-quels-dommages-et-int\u00e9r\u00eats-peuvent-r\u00e9clamer-les-victimes_Page3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2680\" src=\"http:\/\/spoliation.org\/wp-content\/uploads\/2017\/04\/NEXTHOPE-RANARISON-Tsilavo-quels-dommages-et-int\u00e9r\u00eats-peuvent-r\u00e9clamer-les-victimes_Page3.jpg\" alt=\"\" width=\"521\" height=\"913\" \/><\/a><\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #000080;\">D&rsquo;ailleurs sur le site CISCO, c&rsquo;est \u00e9crit que : \u00ab\u00a0Le mat\u00e9riel Cisco peut \u00eatre revendu ou lou\u00e9 librement.\u00a0\u00bb<\/span><\/h1>\n<p><a href=\"http:\/\/spoliation.org\/wp-content\/uploads\/2018\/08\/RANARISON-Tsilavo-CEO-NEXTHOPE-Le-mat\u00e9riel-Cisco-peut-\u00eatre-revendu-ou-lou\u00e9-librement.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3562\" src=\"http:\/\/spoliation.org\/wp-content\/uploads\/2018\/08\/RANARISON-Tsilavo-CEO-NEXTHOPE-Le-mat\u00e9riel-Cisco-peut-\u00eatre-revendu-ou-lou\u00e9-librement.jpg\" alt=\"\" width=\"1128\" height=\"316\" \/><\/a><\/p>\n<h1 style=\"text-align: center;\"><span style=\"color: #0000ff;\">Puisque tout le monde peut vendre des produits Cisco librement sans autorisation : la cour d&rsquo;appel a d\u00e9natur\u00e9 le contenu de l&rsquo;attestation Cisco du 26 novembre 2013 et que la cour de cassation ne peut que casser l&rsquo;arr\u00eat de la cour d&rsquo;appel<\/span><\/h1>\n","protected":false},"excerpt":{"rendered":"<p>Les textes de loi malgaches (article 6 du code de proc\u00e9dure p\u00e9nale et article 181 de la loi 2003-036 r\u00e9gissant les soci\u00e9t\u00e9s commerciales) sont clairs : c&rsquo;est la soci\u00e9t\u00e9 CONNECTIC qui est la victime du soit-disant abus des biens sociaux et non RANARISON Tsilavo, simple associ\u00e9. &nbsp; Mais on se pose quand m\u00eame la question, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3799,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,16],"tags":[],"class_list":["post-2677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ranarison-tsilavo","category-ranarison-tsilavo-ne-peut-pas-se-faire-attribuer-des-interets-civils"],"_links":{"self":[{"href":"https:\/\/www.madagasikara.net\/index.php\/wp-json\/wp\/v2\/posts\/2677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.madagasikara.net\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.madagasikara.net\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.madagasikara.net\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.madagasikara.net\/index.php\/wp-json\/wp\/v2\/comments?post=2677"}],"version-history":[{"count":0,"href":"https:\/\/www.madagasikara.net\/index.php\/wp-json\/wp\/v2\/posts\/2677\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.madagasikara.net\/index.php\/wp-json\/"}],"wp:attachment":[{"href":"https:\/\/www.madagasikara.net\/index.php\/wp-json\/wp\/v2\/media?parent=2677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.madagasikara.net\/index.php\/wp-json\/wp\/v2\/categories?post=2677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.madagasikara.net\/index.php\/wp-json\/wp\/v2\/tags?post=2677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}